{"id":17362,"date":"2026-05-20T13:57:56","date_gmt":"2026-05-20T11:57:56","guid":{"rendered":"https:\/\/macketi.com\/?post_type=product&#038;p=17362"},"modified":"2026-05-20T13:57:56","modified_gmt":"2026-05-20T11:57:56","slug":"quita-manchas-lubrex","status":"publish","type":"product","link":"https:\/\/macketi.com\/en\/product\/quita-manchas-lubrex\/","title":{"rendered":"Quita manchas Lubrex"},"content":{"rendered":"<p data-path-to-node=\"2,0,0\"><b data-path-to-node=\"2,0,0\" data-index-in-node=\"0\">*Marca:<\/b> LUBREX <i data-path-to-node=\"2,0,0\" data-index-in-node=\"14\">home<\/i>.<\/p>\n<p data-path-to-node=\"2,1,0\"><b data-path-to-node=\"2,1,0\" data-index-in-node=\"0\">*Tipo de producto:<\/b> <b data-path-to-node=\"2,1,0\" data-index-in-node=\"18\">Quita Manchas<\/b> (Stain Remover \/ Tira-N\u00f3doas).<\/p>\n<p data-path-to-node=\"2,2,0\"><b data-path-to-node=\"2,2,0\" data-index-in-node=\"0\">*Funci\u00f3n principal:<\/b> Dise\u00f1ado especialmente para tratar manchas en prendas de vestir (como la camisa que se muestra en la imagen) antes del lavado o como tratamiento localizado.<\/p>\n<p data-path-to-node=\"2,3,0\"><b data-path-to-node=\"2,3,0\" data-index-in-node=\"0\">*Beneficio destacado:<\/b> Cuenta con un sello azul que indica <b data-path-to-node=\"2,3,0\" data-index-in-node=\"57\">\u00abNo deja cerco\u00bb<\/b>, lo que significa que el producto est\u00e1 formulado para limpiar la mancha sin dejar aureolas o marcas blanquecinas en el tejido tras su uso.<\/p>\n<p data-path-to-node=\"2,4,0\"><b data-path-to-node=\"2,4,0\" data-index-in-node=\"0\">*Eficacia:<\/b> En el lateral se alcanza a leer que es eficiente contra manchas de tipo graso.<\/p>","protected":false},"excerpt":{"rendered":"<p>Este es un producto especializado para el cuidado de la ropa, dise\u00f1ado para la eliminaci\u00f3n de manchas rebeldes.<\/p>","protected":false},"featured_media":17363,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[355],"product_tag":[],"class_list":["post-17362","product","type-product","status-publish","has-post-thumbnail","product_cat-cuidado-personal","thunk-woo-product-list","opn-qv-enable","th-shop-mania-woo-hover-","open-single-product-tab-horizontal","open-shadow-","open-shadow-hover-","th-shop-mania-single-product-content-left","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/product\/17362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/comments?post=17362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/media\/17363"}],"wp:attachment":[{"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/media?parent=17362"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/product_brand?post=17362"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/product_cat?post=17362"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/product_tag?post=17362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}