{"id":12626,"date":"2025-08-23T13:42:44","date_gmt":"2025-08-23T11:42:44","guid":{"rendered":"https:\/\/macketi.com\/?post_type=product&#038;p=12626"},"modified":"2025-09-06T16:56:11","modified_gmt":"2025-09-06T14:56:11","slug":"ritual-of-fragances-bantu","status":"publish","type":"product","link":"https:\/\/macketi.com\/en\/product\/ritual-of-fragances-bantu\/","title":{"rendered":"Ritual of Fragances: Bant\u00fa"},"content":{"rendered":"<p>Un perfume que despierta poder y sofisticaci\u00f3n. Las notas de maderas nobles se entrelazan con especias c\u00e1lidas, creando un aroma envolvente y magn\u00e9tico.<\/p>\n<p>Misterioso, elegante y profundamente masculino, Es la fragancia del hombre seguro de s\u00ed mismo, que conquista sin esfuerzo y deja una huella inolvidable en cada lugar que pisa<\/p>","protected":false},"excerpt":{"rendered":"<p>Perfume para hombre<\/p>","protected":false},"featured_media":12627,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[506],"product_cat":[489],"product_tag":[],"class_list":["post-12626","product","type-product","status-publish","has-post-thumbnail","product_brand-ritual-of-fragances","product_cat-perfumes","thunk-woo-product-list","opn-qv-enable","th-shop-mania-woo-hover-","open-single-product-tab-horizontal","open-shadow-","open-shadow-hover-","th-shop-mania-single-product-content-left","first","instock","downloadable","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/product\/12626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/comments?post=12626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/media\/12627"}],"wp:attachment":[{"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/media?parent=12626"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/product_brand?post=12626"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/product_cat?post=12626"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/macketi.com\/en\/wp-json\/wp\/v2\/product_tag?post=12626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}